{"id":16,"count":0,"description":"","link":"https:\/\/sanqingniaoo.com\/de\/category\/decoration\/","name":"Dekoration","slug":"decoration","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/sanqingniaoo.com\/de\/wp-json\/wp\/v2\/categories\/16","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanqingniaoo.com\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/sanqingniaoo.com\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/sanqingniaoo.com\/de\/wp-json\/wp\/v2\/posts?categories=16"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}