{"id":29214,"date":"2026-04-08T08:20:25","date_gmt":"2026-04-08T08:20:25","guid":{"rendered":"https:\/\/sanqingniaoo.com\/product\/sweet-roll\/"},"modified":"2026-04-22T09:15:58","modified_gmt":"2026-04-22T09:15:58","slug":"sweet-roll","status":"publish","type":"product","link":"https:\/\/sanqingniaoo.com\/fr\/produit\/sweet-roll\/","title":{"rendered":"Rouleau sucr\u00e9"},"content":{"rendered":"<p>Sweet Roll combine 3 couleurs dans chaque pelote. Le fil est con\u00e7u pour cr\u00e9er de larges rayures dans une r\u00e9p\u00e9tition r\u00e9guli\u00e8re, cr\u00e9ant ainsi toute l'excitation du travail avec plusieurs couleurs, sans le fastidieux tissage de tous ces bouts. Notre gamme de combinaisons de couleurs comprend quelque chose pour tout le monde, des neutres aux pastels en passant par les couleurs vives.<br \/>\nTravaillez confortablement en sachant que ce fil est sans danger pour tout le monde ! Il a pass\u00e9 la norme la plus \u00e9lev\u00e9e, convenant au contact direct avec les peaux les plus sensibles, m\u00eame celles des b\u00e9b\u00e9s et des jeunes enfants.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sweet Roll combines 3 colors in each ball. The yarn is designed to create wide stripes in a regular repeat,<\/p>","protected":false},"featured_media":29212,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[30],"product_tag":[],"class_list":{"0":"post-29214","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-linen-yarn","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/sanqingniaoo.com\/fr\/wp-json\/wp\/v2\/product\/29214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanqingniaoo.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sanqingniaoo.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sanqingniaoo.com\/fr\/wp-json\/wp\/v2\/comments?post=29214"}],"version-history":[{"count":0,"href":"https:\/\/sanqingniaoo.com\/fr\/wp-json\/wp\/v2\/product\/29214\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sanqingniaoo.com\/fr\/wp-json\/wp\/v2\/media\/29212"}],"wp:attachment":[{"href":"https:\/\/sanqingniaoo.com\/fr\/wp-json\/wp\/v2\/media?parent=29214"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sanqingniaoo.com\/fr\/wp-json\/wp\/v2\/product_brand?post=29214"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sanqingniaoo.com\/fr\/wp-json\/wp\/v2\/product_cat?post=29214"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sanqingniaoo.com\/fr\/wp-json\/wp\/v2\/product_tag?post=29214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}